{"id":34685,"date":"2025-07-23T15:00:15","date_gmt":"2025-07-23T15:00:15","guid":{"rendered":"https:\/\/zollas.art\/product\/cork-baseball-cap\/"},"modified":"2025-10-27T16:29:41","modified_gmt":"2025-10-27T16:29:41","slug":"bone-de-basebol-em-cortica","status":"publish","type":"product","link":"https:\/\/zollas.art\/pt-pt\/produto\/bone-de-basebol-em-cortica\/","title":{"rendered":"Bon\u00e9 de basebol em corti\u00e7a"},"content":{"rendered":"<p>Bon\u00e9 de basebol em corti\u00e7a natural.<\/p>\n<p>Estilo desportivo com consci\u00eancia ecol\u00f3gica.<\/p>\n<p>Este bon\u00e9 de basebol \u00e9 feito em corti\u00e7a natural 100% portuguesa, um material leve, resistente e sustent\u00e1vel.<\/p>\n<p>Com design ajust\u00e1vel e confort\u00e1vel, adapta-se facilmente a diferentes tamanhos de cabe\u00e7a.<\/p>\n<p>Ideal para uso di\u00e1rio ou atividades ao ar livre, combina funcionalidade com um visual moderno e natural.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bon\u00e9 de basebol em corti\u00e7a.<\/p>\n","protected":false},"featured_media":31028,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[205],"product_tag":[],"class_list":{"0":"post-34685","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-outros-items","8":"first","9":"instock","10":"shipping-taxable","11":"product-type-variable"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bon\u00e9 de basebol em corti\u00e7a - Zolla<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/zollas.art\/pt-pt\/produto\/bone-de-basebol-em-cortica\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bon\u00e9 de basebol em corti\u00e7a - Zolla\" \/>\n<meta property=\"og:description\" content=\"Bon\u00e9 de basebol em corti\u00e7a.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/zollas.art\/pt-pt\/produto\/bone-de-basebol-em-cortica\/\" \/>\n<meta property=\"og:site_name\" content=\"Zolla\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/artelusa\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-27T16:29:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/zollas.art\/wp-content\/uploads\/2025\/08\/9166.01-H45a.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1100\" \/>\n\t<meta property=\"og:image:height\" content=\"1100\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/zollas.art\/pt-pt\/produto\/bone-de-basebol-em-cortica\/\",\"url\":\"https:\/\/zollas.art\/pt-pt\/produto\/bone-de-basebol-em-cortica\/\",\"name\":\"Bon\u00e9 de basebol em corti\u00e7a - Zolla\",\"isPartOf\":{\"@id\":\"https:\/\/zollas.art\/pt-pt\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/zollas.art\/pt-pt\/produto\/bone-de-basebol-em-cortica\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/zollas.art\/pt-pt\/produto\/bone-de-basebol-em-cortica\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/zollas.art\/wp-content\/uploads\/2025\/08\/9166.01-H45a.webp\",\"datePublished\":\"2025-07-23T15:00:15+00:00\",\"dateModified\":\"2025-10-27T16:29:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/zollas.art\/pt-pt\/produto\/bone-de-basebol-em-cortica\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/zollas.art\/pt-pt\/produto\/bone-de-basebol-em-cortica\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/zollas.art\/pt-pt\/produto\/bone-de-basebol-em-cortica\/#primaryimage\",\"url\":\"https:\/\/zollas.art\/wp-content\/uploads\/2025\/08\/9166.01-H45a.webp\",\"contentUrl\":\"https:\/\/zollas.art\/wp-content\/uploads\/2025\/08\/9166.01-H45a.webp\",\"width\":1100,\"height\":1100},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/zollas.art\/pt-pt\/produto\/bone-de-basebol-em-cortica\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/zollas.art\/pt-pt\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Loja\",\"item\":\"https:\/\/zollas.art\/pt-pt\/loja\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bon\u00e9 de basebol em corti\u00e7a\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/zollas.art\/pt-pt\/#website\",\"url\":\"https:\/\/zollas.art\/pt-pt\/\",\"name\":\"Zolla\",\"description\":\"Eco Friendly cork products with cork 100% natural and PETA approved.\",\"publisher\":{\"@id\":\"https:\/\/zollas.art\/pt-pt\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/zollas.art\/pt-pt\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/zollas.art\/pt-pt\/#organization\",\"name\":\"Zollas\",\"url\":\"https:\/\/zollas.art\/pt-pt\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/zollas.art\/pt-pt\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/zollas.art\/wp-content\/uploads\/2025\/07\/logo_artelusa_318.webp\",\"contentUrl\":\"https:\/\/zollas.art\/wp-content\/uploads\/2025\/07\/logo_artelusa_318.webp\",\"width\":318,\"height\":145,\"caption\":\"Zollas\"},\"image\":{\"@id\":\"https:\/\/zollas.art\/pt-pt\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/artelusa\",\"https:\/\/www.instagram.com\/artelusa\/\",\"https:\/\/www.youtube.com\/channel\/UCzyslgcvHAI_kQ_hkae5JIw\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bon\u00e9 de basebol em corti\u00e7a - Zolla","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/zollas.art\/pt-pt\/produto\/bone-de-basebol-em-cortica\/","og_locale":"pt_PT","og_type":"article","og_title":"Bon\u00e9 de basebol em corti\u00e7a - Zolla","og_description":"Bon\u00e9 de basebol em corti\u00e7a.","og_url":"https:\/\/zollas.art\/pt-pt\/produto\/bone-de-basebol-em-cortica\/","og_site_name":"Zolla","article_publisher":"https:\/\/www.facebook.com\/artelusa","article_modified_time":"2025-10-27T16:29:41+00:00","og_image":[{"width":1100,"height":1100,"url":"https:\/\/zollas.art\/wp-content\/uploads\/2025\/08\/9166.01-H45a.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/zollas.art\/pt-pt\/produto\/bone-de-basebol-em-cortica\/","url":"https:\/\/zollas.art\/pt-pt\/produto\/bone-de-basebol-em-cortica\/","name":"Bon\u00e9 de basebol em corti\u00e7a - Zolla","isPartOf":{"@id":"https:\/\/zollas.art\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/zollas.art\/pt-pt\/produto\/bone-de-basebol-em-cortica\/#primaryimage"},"image":{"@id":"https:\/\/zollas.art\/pt-pt\/produto\/bone-de-basebol-em-cortica\/#primaryimage"},"thumbnailUrl":"https:\/\/zollas.art\/wp-content\/uploads\/2025\/08\/9166.01-H45a.webp","datePublished":"2025-07-23T15:00:15+00:00","dateModified":"2025-10-27T16:29:41+00:00","breadcrumb":{"@id":"https:\/\/zollas.art\/pt-pt\/produto\/bone-de-basebol-em-cortica\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/zollas.art\/pt-pt\/produto\/bone-de-basebol-em-cortica\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/zollas.art\/pt-pt\/produto\/bone-de-basebol-em-cortica\/#primaryimage","url":"https:\/\/zollas.art\/wp-content\/uploads\/2025\/08\/9166.01-H45a.webp","contentUrl":"https:\/\/zollas.art\/wp-content\/uploads\/2025\/08\/9166.01-H45a.webp","width":1100,"height":1100},{"@type":"BreadcrumbList","@id":"https:\/\/zollas.art\/pt-pt\/produto\/bone-de-basebol-em-cortica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/zollas.art\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Loja","item":"https:\/\/zollas.art\/pt-pt\/loja\/"},{"@type":"ListItem","position":3,"name":"Bon\u00e9 de basebol em corti\u00e7a"}]},{"@type":"WebSite","@id":"https:\/\/zollas.art\/pt-pt\/#website","url":"https:\/\/zollas.art\/pt-pt\/","name":"Zolla","description":"Eco Friendly cork products with cork 100% natural and PETA approved.","publisher":{"@id":"https:\/\/zollas.art\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/zollas.art\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/zollas.art\/pt-pt\/#organization","name":"Zollas","url":"https:\/\/zollas.art\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/zollas.art\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/zollas.art\/wp-content\/uploads\/2025\/07\/logo_artelusa_318.webp","contentUrl":"https:\/\/zollas.art\/wp-content\/uploads\/2025\/07\/logo_artelusa_318.webp","width":318,"height":145,"caption":"Zollas"},"image":{"@id":"https:\/\/zollas.art\/pt-pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/artelusa","https:\/\/www.instagram.com\/artelusa\/","https:\/\/www.youtube.com\/channel\/UCzyslgcvHAI_kQ_hkae5JIw"]}]}},"_links":{"self":[{"href":"https:\/\/zollas.art\/pt-pt\/wp-json\/wp\/v2\/product\/34685","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zollas.art\/pt-pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/zollas.art\/pt-pt\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/zollas.art\/pt-pt\/wp-json\/wp\/v2\/comments?post=34685"}],"version-history":[{"count":0,"href":"https:\/\/zollas.art\/pt-pt\/wp-json\/wp\/v2\/product\/34685\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zollas.art\/pt-pt\/wp-json\/wp\/v2\/media\/31028"}],"wp:attachment":[{"href":"https:\/\/zollas.art\/pt-pt\/wp-json\/wp\/v2\/media?parent=34685"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/zollas.art\/pt-pt\/wp-json\/wp\/v2\/product_brand?post=34685"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/zollas.art\/pt-pt\/wp-json\/wp\/v2\/product_cat?post=34685"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/zollas.art\/pt-pt\/wp-json\/wp\/v2\/product_tag?post=34685"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}